{"id":2512,"date":"2003-09-16T17:20:09","date_gmt":"2003-09-16T17:20:09","guid":{"rendered":"http:\/\/xmau.com\/wp\/notiziole\/2003\/09\/16\/alitalia\/"},"modified":"2003-09-16T17:20:09","modified_gmt":"2003-09-16T17:20:09","slug":"alitalia","status":"publish","type":"post","link":"https:\/\/xmau.com\/wp\/notiziole\/2003\/09\/16\/alitalia\/","title":{"rendered":"Alitalia"},"content":{"rendered":"<p>Lo so, mi ripeto. Che ci posso fare, per\u00f2? Stavolta il volo delle 8 \u00e8 partito alle 8:35. Ma non perch\u00e9 non ci fosse l&#8217;aereo: la chiamata \u00e8 stata regolarmente fatta alle 7:35, anzi con qualche minuto di anticipo. Ma se si vede gente (e non una singola persona) salire <em>alle 8:05<\/em> significa che la nostra compagnia di bandiera  decide scientemente di ritardare i voli. Allora non rompano le palle, costringano ad avere 40 minuti di anticipo rispetto alla partenza e non i 25 attuali, e li facciano rispettare.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo so, mi ripeto. Che ci posso fare, per\u00f2? Stavolta il volo delle 8 \u00e8 partito alle 8:35. Ma non perch\u00e9 non ci fosse l&#8217;aereo: la chiamata \u00e8 stata regolarmente fatta alle 7:35, anzi con qualche minuto di anticipo. Ma se si vede gente (e non una singola persona) salire alle 8:05 significa che la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":3,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[8],"tags":[],"class_list":["post-2512","post","type-post","status-publish","format-standard","hentry","category-y2003_pipponi"],"modified_by":null,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/s6hcSh-alitalia","jetpack-related-posts":[{"id":16696,"url":"https:\/\/xmau.com\/wp\/notiziole\/2018\/05\/03\/lapp-di-posteitaliane-pensa-agli-umarell\/","url_meta":{"origin":2512,"position":0},"title":"L&#8217;app di PosteItaliane pensa agli umarell","author":".mau.","date":"2018-05-03","format":false,"excerpt":"e non permette di prenotare troppo presto","rel":"","context":"In &quot;pipponi&quot;","block_context":{"text":"pipponi","link":"https:\/\/xmau.com\/wp\/notiziole\/category\/pipponi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/xmau.com\/wp\/notiziole\/wp-content\/uploads\/sites\/6\/2018\/04\/greendot.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4247,"url":"https:\/\/xmau.com\/wp\/notiziole\/2006\/07\/03\/troppi_anticipi\/","url_meta":{"origin":2512,"position":1},"title":"troppi anticipi?","author":".mau.","date":"2006-07-03","format":false,"excerpt":"Com'\u00e8 possibile che un tram sia in anticipo di otto minuti sulla sua tabella di marcia?","rel":"","context":"In &quot;trasporti&quot;","block_context":{"text":"trasporti","link":"https:\/\/xmau.com\/wp\/notiziole\/category\/trasporti\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1968,"url":"https:\/\/xmau.com\/wp\/notiziole\/2002\/03\/23\/trenitalia_al_muro\/","url_meta":{"origin":2512,"position":2},"title":"Trenitalia: al muro!","author":".mau.","date":"2002-03-23","format":false,"excerpt":"Uno degli effetti collaterali della foratura di gioved\u00ec scorso \u00e8 stata la mia impossibilit\u00e0 di andare a comprare il biglietto del treno per Torino. Ho cos\u00ec pensato: vabb\u00e9, sabato mi sveglio all'alba (7:15), esco alle 8, arrivo alle 8:20 in stazione e ho un quarto d'ora per comprare il biglietto.\u2026","rel":"","context":"In &quot;2001-02&quot;","block_context":{"text":"2001-02","link":"https:\/\/xmau.com\/wp\/notiziole\/category\/varie\/varie-2001-02\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":14988,"url":"https:\/\/xmau.com\/wp\/notiziole\/2017\/06\/14\/centri-estivi-comunali-e-progetto-a\/","url_meta":{"origin":2512,"position":3},"title":"Centri estivi comunali e Progetto A","author":".mau.","date":"2017-06-14","format":false,"excerpt":"Incapacit\u00e0 gestionale totale","rel":"","context":"In &quot;io&quot;","block_context":{"text":"io","link":"https:\/\/xmau.com\/wp\/notiziole\/category\/io\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3530,"url":"https:\/\/xmau.com\/wp\/notiziole\/2005\/06\/06\/macch_clienti\/","url_meta":{"origin":2512,"position":4},"title":"Macch\u00e9 &#8220;clienti&#8221;","author":".mau.","date":"2005-06-06","format":false,"excerpt":"L'ATM milanese si distingue come al solito per l'informazione. [...]","rel":"","context":"Articolo simile","block_context":{"text":"Articolo simile","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4391,"url":"https:\/\/xmau.com\/wp\/notiziole\/2006\/09\/15\/qual_quella_parola\/","url_meta":{"origin":2512,"position":5},"title":"qual \u00e8 quella parola?","author":".mau.","date":"2006-09-15","format":false,"excerpt":"Se uno sciopero inizia alle 8:45, come si possono chiamare i tranvieri che alle 8:25 tornano in deposito?","rel":"","context":"In &quot;trasporti&quot;","block_context":{"text":"trasporti","link":"https:\/\/xmau.com\/wp\/notiziole\/category\/trasporti\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/xmau.com\/wp\/notiziole\/wp-json\/wp\/v2\/posts\/2512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xmau.com\/wp\/notiziole\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xmau.com\/wp\/notiziole\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xmau.com\/wp\/notiziole\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/xmau.com\/wp\/notiziole\/wp-json\/wp\/v2\/comments?post=2512"}],"version-history":[{"count":0,"href":"https:\/\/xmau.com\/wp\/notiziole\/wp-json\/wp\/v2\/posts\/2512\/revisions"}],"wp:attachment":[{"href":"https:\/\/xmau.com\/wp\/notiziole\/wp-json\/wp\/v2\/media?parent=2512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xmau.com\/wp\/notiziole\/wp-json\/wp\/v2\/categories?post=2512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xmau.com\/wp\/notiziole\/wp-json\/wp\/v2\/tags?post=2512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}