{"id":2406,"date":"2003-06-30T09:56:31","date_gmt":"2003-06-30T09:56:31","guid":{"rendered":"http:\/\/xmau.com\/wp\/notiziole\/2003\/06\/30\/milioni_miliardi\/"},"modified":"2003-06-30T09:56:31","modified_gmt":"2003-06-30T09:56:31","slug":"milioni_miliardi","status":"publish","type":"post","link":"https:\/\/xmau.com\/wp\/notiziole\/2003\/06\/30\/milioni_miliardi\/","title":{"rendered":"milioni? miliardi?"},"content":{"rendered":"<p>Trafiletto da <em>Metro<\/em> di oggi. Titolo: &#8220;Tredici milioni nel 2001 sono andati in fumo&#8221;. I 13 milioni di euro sarebbero stati la spesa per sigari e sigarette degli italiani due anni fa. Notate nulla di strano? Supponendo che a fumare sia un quarto degli italiani, si otterrebbe che ciascun fumatore spende meno di un euro l&#8217;anno!<br \/>\nCome controprova, proseguendo nell&#8217;articolo si legge che sono state acquistate 10 miliardi di sigarette oltre ai sigari, e quindi il prezzo di una sigaretta sarebbe di circa 0.13 eurocent.<br \/>\nNon occorrono grandi conoscenze matematiche per accorgersene, vero?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trafiletto da Metro di oggi. Titolo: &#8220;Tredici milioni nel 2001 sono andati in fumo&#8221;. I 13 milioni di euro sarebbero stati la spesa per sigari e sigarette degli italiani due anni fa. Notate nulla di strano? Supponendo che a fumare sia un quarto degli italiani, si otterrebbe che ciascun fumatore spende meno di un euro [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":3,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[14],"tags":[],"class_list":["post-2406","post","type-post","status-publish","format-standard","hentry","category-povera_matematica"],"modified_by":null,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p6hcSh-CO","jetpack-related-posts":[{"id":5417,"url":"https:\/\/xmau.com\/wp\/notiziole\/2007\/10\/22\/incendio\/","url_meta":{"origin":2406,"position":0},"title":"incendio!","author":".mau.","date":"2007-10-22","format":false,"excerpt":"o almeno, \u00e8 suonato l'allarme antincendio...","rel":"","context":"In &quot;io-2007&quot;","block_context":{"text":"io-2007","link":"https:\/\/xmau.com\/wp\/notiziole\/category\/io\/io-2007\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":9128,"url":"https:\/\/xmau.com\/wp\/notiziole\/2012\/12\/23\/i_conti_della_s\/","url_meta":{"origin":2406,"position":1},"title":"I conti della serva","author":".mau.","date":"2012-12-23","format":false,"excerpt":"Un po' di fact checking su Silvio.","rel":"","context":"In &quot;politica&quot;","block_context":{"text":"politica","link":"https:\/\/xmau.com\/wp\/notiziole\/category\/politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":6454,"url":"https:\/\/xmau.com\/wp\/notiziole\/2008\/10\/16\/levoluzione_deg\/","url_meta":{"origin":2406,"position":2},"title":"L&#8217;evoluzione degli spalloni","author":".mau.","date":"2008-10-16","format":false,"excerpt":"un sito per acquistare sigarette a prezzi stracciati \u00e8 svizzero.","rel":"","context":"In &quot;curiosit\u00e0-2008&quot;","block_context":{"text":"curiosit\u00e0-2008","link":"https:\/\/xmau.com\/wp\/notiziole\/category\/curiosita\/curiosita-2008\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5866,"url":"https:\/\/xmau.com\/wp\/notiziole\/2008\/03\/25\/niente_sigarett\/","url_meta":{"origin":2406,"position":3},"title":"Niente sigarette, siamo inglesi","author":".mau.","date":"2008-03-25","format":false,"excerpt":"In Gran Bretagna pensano che evitando di mostrare le sigarette i ragazzi non inizieranno a fumare.","rel":"","context":"In &quot;pipponi&quot;","block_context":{"text":"pipponi","link":"https:\/\/xmau.com\/wp\/notiziole\/category\/pipponi\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4815,"url":"https:\/\/xmau.com\/wp\/notiziole\/2007\/03\/13\/marlboro_quality_line\/","url_meta":{"origin":2406,"position":4},"title":"Marlboro Quality Line","author":".mau.","date":"2007-03-13","format":false,"excerpt":"Restyling dei pacchetti di sigarette: fortuna che l'hanno scritto, altrimenti chi se ne accorgeva?","rel":"","context":"In &quot;curiosit\u00e0-2007&quot;","block_context":{"text":"curiosit\u00e0-2007","link":"https:\/\/xmau.com\/wp\/notiziole\/category\/curiosita\/curiosita-2007\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2601,"url":"https:\/\/xmau.com\/wp\/notiziole\/2003\/11\/10\/oggi_sui_quotidiani_aggratis\/","url_meta":{"origin":2406,"position":5},"title":"Oggi sui quotidiani aggratis","author":".mau.","date":"2003-11-10","format":false,"excerpt":"Giornata relativamente ricca per i quotidiani gratuiti, oggi. Iniziamo con Leggo, che in un trafiletto della pagina dedicata ai chewing gum afferma che nel 2011 avremo in commercio le cicche al Sildenafil citrato (il Viagra: se siete arrivati qui con una ricerca, avete sbagliato sito...). Nessuna curiosit\u00e0 su perch\u00e9 ci\u2026","rel":"","context":"In &quot;y2003_curiosita'&quot;","block_context":{"text":"y2003_curiosita'","link":"https:\/\/xmau.com\/wp\/notiziole\/category\/y2003_curiosita\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/xmau.com\/wp\/notiziole\/wp-json\/wp\/v2\/posts\/2406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xmau.com\/wp\/notiziole\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xmau.com\/wp\/notiziole\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xmau.com\/wp\/notiziole\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/xmau.com\/wp\/notiziole\/wp-json\/wp\/v2\/comments?post=2406"}],"version-history":[{"count":0,"href":"https:\/\/xmau.com\/wp\/notiziole\/wp-json\/wp\/v2\/posts\/2406\/revisions"}],"wp:attachment":[{"href":"https:\/\/xmau.com\/wp\/notiziole\/wp-json\/wp\/v2\/media?parent=2406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xmau.com\/wp\/notiziole\/wp-json\/wp\/v2\/categories?post=2406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xmau.com\/wp\/notiziole\/wp-json\/wp\/v2\/tags?post=2406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}