{"id":8808,"date":"2012-03-26T07:00:00","date_gmt":"2012-03-26T07:00:00","guid":{"rendered":"http:\/\/xmau.com\/wp\/notiziole\/2012\/03\/26\/faligi_editore\/"},"modified":"2012-03-26T07:00:00","modified_gmt":"2012-03-26T07:00:00","slug":"faligi_editore","status":"publish","type":"post","link":"https:\/\/xmau.com\/notiziole\/2012\/03\/26\/faligi_editore\/","title":{"rendered":"Faligi editore"},"content":{"rendered":"<p>\u00c8 luned\u00ec mattina, quindi posso sperare che i miei ventun lettori siano un po&#8217; pi\u00f9 interessati che durante il weekend a sentire una storiella edificante, liberamente tratta da <a href=\"http:\/\/nopeanuts.wordpress.com\/2012\/03\/23\/faligi-editore-if-the-shoe-fits\/\">qui<\/a>. Anche se non avete mai tradotto nulla pi\u00f9 che &#8220;the cat is on the table&#8221;, vi consiglio di leggerla.<br \/>\nC&#8217;era una volta una casa editrice aostana, Faligi Editore, che pubblicava solamente ebook. Come loro stessi <a href=\"http:\/\/www.faligi.eu\/aboutus.php\">spiegavano<\/a>, \u00abcon abilit\u00e0 hanno diffuso un nuovo modo di fare editoria, dando un nuovo orientamento culturale all\u0092editoria Europea con la pubblicazione di scrittori esordienti la cui opera \u00e8 tradotta in 5 lingue\u00bb; d&#8217;altra parte \u00abLa casa editrice \u00e8 la prima in Europa in grado di accomunare scrittori e traduttori letterari dalle personalit\u00e0 eclettiche e dal pensiero moderno.\u00bb (dicevano sempre loro: io non oserei toccare una virgola, e mi avvalgo del diritto di citazione). Ma naturalmente questi traduttori letterari dalle personalit\u00e0 eclettiche e dal pensiero moderno bisogna trovarli, e soprattutto bisogna scremare certi wannabe: cos\u00ec alla Faligi pensarono di <a href=\"http:\/\/www.faligi.eu\/corsi.php\">selezionarli<\/a> accuratamente. L&#8217;aspirante traduttore pagava 160 euro e aveva il diritto di partecipare a un &#8220;Creative Meeting&#8221; di selezione traduttori: tre ore passate nella ridente cittadina di Chivasso, seguite da \u00abuna prova di traduzione (da svolgere a casa nel mese successivo al corso)\u00bb. Se era stato sufficientemente bravo, generalmente (dicevano loro) \u00abal traduttore sar\u00e0 inviato un contratto di edizione per un libr0 (sic) da tradurre in un anno solare\u00bb; il tutto con un contratto che &#8211; secondo <a href=\"http:\/\/nopeanuts.wordpress.com\/2011\/10\/17\/faligi-editore\/\">le malelingue<\/a> che sempre ci sono &#8211; \u00e8 a royalty, quindi a una percentuale sul numero di copie vendute: questo significa che per l&#8217;editore il rischio era minimale, dato che i costi per produrre un ebook sono irrisori, e che il Bravo Traduttore si sarebbe visto pagare noccioline per il suo lavoro.<br \/>\nLa mia amica Isa Zani, dopo aver letto quanto scritto da quelle malelingue, ha pensato che in fin dei conti lei \u00e8 una traduttrice e che si sarebbe potuta esercitare utilmente nella <a href=\"http:\/\/nopeanuts.wordpress.com\/2011\/10\/19\/ci-vorrebbe-una-legge-faligi\/\">traduzione in italiano<\/a>, tanto per mantenersi in forma. Pass\u00f2 un mese, due, tre: un uccellino port\u00f2 la notizia in giro per le valli, e un giorno un avvocato <a href=\"http:\/\/nopeanuts.files.wordpress.com\/2012\/03\/faligi-letter1.pdf\">scrisse una lettera di cease-<s>or<\/s>and-desist<\/a>, accusando Isa di diffamazione e di concorrenza sleale poich\u00e9 lei svolgerebbe &#8220;corsi per traduttori&#8221;. Attenzione: la lettera <b>non \u00e8 stata inviata al sito<\/b>, ma solo alla traduttrice. Potete scegliere voi se il motivo \u00e8 stato perch\u00e9 alla Faligi non avevano a disposizione un traduttore per leggere l&#8217;originale, se perch\u00e9 tanto si sa che in Italia gli unici a capire l&#8217;inglese sono i traduttori, o per un&#8217;altra ragione sicuramente molto pi\u00f9 intelligente di quelle che ho trovato io.<br \/>\nIsa \u00e8 un donnino determinato, e ha <a href=\"http:\/\/nopeanuts.files.wordpress.com\/2012\/03\/zani-capalbo.pdf\">risposto<\/a> per le rime: mi dispiace solo che lei abbia creato un file pdf di 8 megabyte per una singola pagina di testo, ma sono certo che si ingegner\u00e0 per ridurne la dimensione. L&#8217;altro mio amico Daniele Gewurz ha iniziato a <a href=\"http:\/\/pignuoli.blogspot.it\/2012\/03\/faligi-e-gli-effetti-dellillecita.html\">diffondere la notizia<\/a>; pure Giovanni Angelo Jonvalli (che non conosco, non \u00e8 che tutti siano miei amici) ha <a href=\"http:\/\/jonvalli.blogspot.it\/2012\/03\/diffidare-dei-diffidanti.html\">ritradotto il post<\/a> sperando di entrare nell&#8217;esclusivo club dei <s>minacciati<\/s> citati dalla Faligi. Io, come i miei ventun lettori sanno, ho anche fatto il traduttore, pur non avendo mai seguito un &#8220;Creative Meeting&#8221;. Presumo che non ci siano gli estremi di una truffa esattamente come non ci sono estremi di truffa nelle case editrici che si fanno pagare per pubblicare il tuo capolavoro; in fin dei conti \u00e8 tutto spiegato chiaramente. Ci\u00f2 detto, &#8220;offerte&#8221; come queste sono semplicemente una fregatura per il poveretto che ci capita sotto. Ma tanto voi non siete traduttori, vero?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>pagare per diventare traduttori non \u00e8 una truffa, anche se in cambio non viene garantito nulla.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":3,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[535],"tags":[],"class_list":["post-8808","post","type-post","status-publish","format-standard","hentry","category-pipponi"],"modified_by":null,"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/phh2yV-2i4","jetpack-related-posts":[{"id":32550,"url":"https:\/\/xmau.com\/notiziole\/2025\/05\/20\/stocazzo-editore\/","url_meta":{"origin":8808,"position":0},"title":"Stocazzo Editore","author":".mau.","date":"2025-05-20","format":false,"excerpt":"Un autoeditore che fa le cose davvero in grande.","rel":"","context":"In &quot;curiosita'&quot;","block_context":{"text":"curiosita'","link":"https:\/\/xmau.com\/notiziole\/category\/curiosita\/"},"img":{"alt_text":"il logo di Stocazzo Editore","src":"https:\/\/i0.wp.com\/xmau.com\/notiziole\/wp-content\/uploads\/sites\/6\/2025\/05\/stocazzo.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":12535,"url":"https:\/\/xmau.com\/notiziole\/2016\/02\/13\/_sullorlo-del-precipizio_-libro\/","url_meta":{"origin":8808,"position":1},"title":"_Sull&#8217;orlo del precipizio_ (libro)","author":".mau.","date":"2016-02-13","format":false,"excerpt":"Distopia o possibile realt\u00e0?","rel":"","context":"In &quot;rec-2016&quot;","block_context":{"text":"rec-2016","link":"https:\/\/xmau.com\/notiziole\/category\/recensioni\/recensioni-2016\/"},"img":{"alt_text":"9788838934834","src":"https:\/\/i0.wp.com\/xmau.com\/notiziole\/wp-content\/uploads\/sites\/6\/2016\/02\/9788838934834.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10142,"url":"https:\/\/xmau.com\/notiziole\/2014\/05\/28\/come-fare-i-soldi\/","url_meta":{"origin":8808,"position":2},"title":"Come fare i soldi","author":".mau.","date":"2014-05-28","format":false,"excerpt":"Come fare soldi se sei un editore di materiale scientifico","rel":"","context":"In &quot;pipponi&quot;","block_context":{"text":"pipponi","link":"https:\/\/xmau.com\/notiziole\/category\/pipponi\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":18665,"url":"https:\/\/xmau.com\/notiziole\/2019\/05\/08\/altaforte\/","url_meta":{"origin":8808,"position":3},"title":"Altaforte","author":".mau.","date":"2019-05-08","format":false,"excerpt":"Alla faccia della pubblicit\u00e0.","rel":"","context":"In &quot;sfrucugliate&quot;","block_context":{"text":"sfrucugliate","link":"https:\/\/xmau.com\/notiziole\/category\/sfrucugliate\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":23733,"url":"https:\/\/xmau.com\/notiziole\/2022\/03\/05\/per-un-umanesimo-scientifico-libro\/","url_meta":{"origin":8808,"position":4},"title":"Per un umanesimo scientifico (libro)","author":".mau.","date":"2022-03-05","format":false,"excerpt":"somiglianze e differenze tra l'editoria attuale e quella dell'immediato dopoguerra","rel":"","context":"In &quot;rec-2022&quot;","block_context":{"text":"rec-2022","link":"https:\/\/xmau.com\/notiziole\/category\/recensioni\/rec-2022\/"},"img":{"alt_text":"copertina","src":"https:\/\/i0.wp.com\/xmau.com\/notiziole\/wp-content\/uploads\/sites\/6\/2022\/02\/9788806202811.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":11998,"url":"https:\/\/xmau.com\/notiziole\/2015\/10\/07\/editori-attenti-ai-lettori\/","url_meta":{"origin":8808,"position":5},"title":"Editori attenti ai lettori","author":".mau.","date":"2015-10-07","format":false,"excerpt":"Kudos a Bollati Boringhieri","rel":"","context":"In &quot;varie&quot;","block_context":{"text":"varie","link":"https:\/\/xmau.com\/notiziole\/category\/varie\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/posts\/8808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/comments?post=8808"}],"version-history":[{"count":0,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/posts\/8808\/revisions"}],"wp:attachment":[{"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/media?parent=8808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/categories?post=8808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/tags?post=8808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}