{"id":8786,"date":"2012-03-25T07:00:00","date_gmt":"2012-03-25T07:00:00","guid":{"rendered":"http:\/\/xmau.com\/wp\/notiziole\/2012\/03\/25\/problema_della_8\/"},"modified":"2016-05-31T12:18:46","modified_gmt":"2016-05-31T10:18:46","slug":"problema_della_8","status":"publish","type":"post","link":"https:\/\/xmau.com\/notiziole\/2012\/03\/25\/problema_della_8\/","title":{"rendered":"Problema della domenica: La lettera mancante"},"content":{"rendered":"<p>Quale lettera deve essere sostituita al punto interrogativo per completare la figura?<br \/>\n<img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/xmau.com\/mate\/problemi\/q017a.png\" alt=\"[le quattro righe: I-d; P-m; E-g; A-?]\" \/><br \/>\n(un aiutino lo trovate sul mio sito, alla pagina <a href=\"http:\/\/xmau.com\/mate\/problemi\/p017.html\">http:\/\/xmau.com\/mate\/problemi\/p017.html<\/a>; la risposta verr\u00e0 postata l\u00ec il prossimo mercoled\u00ec)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>un quiz di logica, senza nessun trucco<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":3,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[74,920],"tags":[],"class_list":["post-8786","post","type-post","status-publish","format-standard","hentry","category-giochi","category-giochi-2012"],"modified_by":null,"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/phh2yV-2hI","jetpack-related-posts":[{"id":10949,"url":"https:\/\/xmau.com\/notiziole\/2015\/01\/11\/quizzino-della-domenica-lettere\/","url_meta":{"origin":8786,"position":0},"title":"Quizzino della domenica: lettere","author":".mau.","date":"2015-01-11","format":false,"excerpt":"Ho diviso l'alfabeto maiuscolo (scritto in Arial Rounded MT Bold) in due parti: la prima comprende le lettere AEFHKTXY, la seconda tutte le altre. Riuscite a scoprire la regola che ho usato? (un aiutino lo trovate sul mio sito, alla pagina http:\/\/xmau.com\/quizzini\/p160.html; la risposta verr\u00e0 postata l\u00ec il prossimo mercoled\u00ec.\u2026","rel":"","context":"In &quot;giochi&quot;","block_context":{"text":"giochi","link":"https:\/\/xmau.com\/notiziole\/category\/giochi\/"},"img":{"alt_text":"q160a","src":"https:\/\/i0.wp.com\/xmau.com\/notiziole\/wp-content\/uploads\/sites\/6\/2015\/01\/q160a.png?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/xmau.com\/notiziole\/wp-content\/uploads\/sites\/6\/2015\/01\/q160a.png?resize=350%2C200 1x, https:\/\/i0.wp.com\/xmau.com\/notiziole\/wp-content\/uploads\/sites\/6\/2015\/01\/q160a.png?resize=525%2C300 1.5x"},"classes":[]},{"id":8906,"url":"https:\/\/xmau.com\/notiziole\/2012\/06\/24\/quizzino_della_6\/","url_meta":{"origin":8786,"position":1},"title":"Quizzino della domenica: la lettera mancante","author":".mau.","date":"2012-06-24","format":false,"excerpt":"Quale sar\u00e0 la lettera successiva nella successione qui sotto? Q - S - L - L - S - N - S - Q - ___ (un aiutino lo trovate sul mio sito, alla pagina http:\/\/xmau.com\/mate\/problemi\/p040.html; la risposta verr\u00e0 postata l\u00ec il prossimo mercoled\u00ec.)","rel":"","context":"In &quot;giochi&quot;","block_context":{"text":"giochi","link":"https:\/\/xmau.com\/notiziole\/category\/giochi\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":23189,"url":"https:\/\/xmau.com\/notiziole\/2022\/02\/20\/quizzino-della-domenica-lettere-cartacee\/","url_meta":{"origin":8786,"position":2},"title":"Quizzino della domenica: Lettere cartacee","author":".mau.","date":"2022-02-20","format":false,"excerpt":"Negli anni '70 del secolo scorso due pensionate, una olandese e una statunitense, si scrivevano lettere (di carta, mica c'era Internet per tutti!) raccontandosi le avventure dei propri nipoti. Avevano per\u00f2 un problema: la prima di solito scriveva la data in formato gg-mm-aaaa, la seconda invece in formato mm-gg-aaaa e\u2026","rel":"","context":"In &quot;giochi&quot;","block_context":{"text":"giochi","link":"https:\/\/xmau.com\/notiziole\/category\/giochi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/xmau.com\/notiziole\/wp-content\/uploads\/sites\/6\/2022\/02\/q569a.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":22069,"url":"https:\/\/xmau.com\/notiziole\/2021\/05\/02\/quizzino-della-domenica-gang\/","url_meta":{"origin":8786,"position":3},"title":"Quizzino della domenica: GANG","author":".mau.","date":"2021-05-02","format":false,"excerpt":"Risolvete (senza forza bruta...) il seguente problema di criptoaritmetica: AN \u00d7 NA = GANG. Come sempre, a lettera uguale corrisponde cifra uguale, e a lettere diverse corrispondono cifre diverse. (trovate un aiutino sul mio sito, alla pagina http:\/\/xmau.com\/quizzini\/p517.html; la risposta verr\u00e0 postata l\u00ec il prossimo mercoled\u00ec. Problema da Math StackExchange)","rel":"","context":"In &quot;giochi&quot;","block_context":{"text":"giochi","link":"https:\/\/xmau.com\/notiziole\/category\/giochi\/"},"img":{"alt_text":"ANxNA=GANG","src":"https:\/\/i0.wp.com\/xmau.com\/notiziole\/wp-content\/uploads\/sites\/6\/2021\/04\/q517a-1.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":14134,"url":"https:\/\/xmau.com\/notiziole\/2017\/01\/08\/quizzino-della-domenica-lettere-2\/","url_meta":{"origin":8786,"position":4},"title":"Quizzino della domenica: Lettere 2","author":".mau.","date":"2017-01-08","format":false,"excerpt":"Ho gi\u00e0 fatto un quizzino dividendo l'alfabeto in due parti. Stavolta ho cambiato font (\u00e8 Calibri) e suddivisione. Riuscite a indovinarla? (un aiutino lo trovate sul mio sito, alla pagina http:\/\/xmau.com\/quizzini\/p225.html; la risposta verr\u00e0 postata l\u00ec il prossimo mercoled\u00ec. Problema tratto da Johnny Ball, Think of a Number)","rel":"","context":"In &quot;giochi&quot;","block_context":{"text":"giochi","link":"https:\/\/xmau.com\/notiziole\/category\/giochi\/"},"img":{"alt_text":"[AEFHIKLMNTVWXYZ | BCDGJOPQRSU]","src":"https:\/\/i0.wp.com\/xmau.com\/notiziole\/wp-content\/uploads\/sites\/6\/2016\/12\/q224a.png?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/xmau.com\/notiziole\/wp-content\/uploads\/sites\/6\/2016\/12\/q224a.png?resize=350%2C200 1x, https:\/\/i0.wp.com\/xmau.com\/notiziole\/wp-content\/uploads\/sites\/6\/2016\/12\/q224a.png?resize=525%2C300 1.5x"},"classes":[]},{"id":22275,"url":"https:\/\/xmau.com\/notiziole\/2021\/06\/13\/quizzino-della-domenica-meta-alfabeto\/","url_meta":{"origin":8786,"position":5},"title":"Quizzino della domenica: Met\u00e0 alfabeto","author":".mau.","date":"2021-06-13","format":false,"excerpt":"Esistono citt\u00e0 italiane il cui nome contiene solo lettere dalla prima met\u00e0 dell'alfabeto (dalla A alla M, visto che l'alfabeto italiano ha 21 lettere e non si pu\u00f2 dividere esattamente a met\u00e0)? E il cui nome contiene solo lettere dalla seconda met\u00e0 dell'alfabeto? (trovate un aiutino sul mio sito, alla\u2026","rel":"","context":"In &quot;giochi&quot;","block_context":{"text":"giochi","link":"https:\/\/xmau.com\/notiziole\/category\/giochi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/xmau.com\/notiziole\/wp-content\/uploads\/sites\/6\/2021\/05\/q523a.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/posts\/8786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/comments?post=8786"}],"version-history":[{"count":0,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/posts\/8786\/revisions"}],"wp:attachment":[{"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/media?parent=8786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/categories?post=8786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/tags?post=8786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}