{"id":8500,"date":"2011-08-11T07:00:00","date_gmt":"2011-08-11T07:00:00","guid":{"rendered":"http:\/\/xmau.com\/wp\/notiziole\/2011\/08\/11\/the_prime_pages\/"},"modified":"2011-08-11T07:00:00","modified_gmt":"2011-08-11T07:00:00","slug":"the_prime_pages","status":"publish","type":"post","link":"https:\/\/xmau.com\/notiziole\/2011\/08\/11\/the_prime_pages\/","title":{"rendered":"The Prime Pages"},"content":{"rendered":"<p>A Chris K. Caldwell piacciono i numeri primi. E piacciono anche le classifiche, direi. Infatti nel suo sito <a href=\"http:\/\/primes.utm.edu\/\">The Prime Pages<\/a> raccoglie informazioni di ogni tipo sui numeri primi, dalle classifiche di ogni tipo (non solo i 5000 numeri primi pi\u00f9 grandi trovati, ma anche molte Top 20 per categorie specifiche) ad alcune informazioni di base sull&#8217;ipotesi di Riemann, dalle congetture sui primi a un test di primalit\u00e0 per numeri (relativamente) piccoli &#8211; per esempio 20110811070001 non \u00e8 primo, anche se il programma non indica i suoi fattori ma solo che non ha passato un test di primalit\u00e0.<br \/>\nA cosa serve tutto questo? A nulla, ma volete mettere scoprire che <a href=\"http:\/\/primes.utm.edu\/curios\/index.php?start=17&amp;stop=36\">11333555557777777<\/a> \u00e8 un numero primo? (e peccato per l&#8217;1 di troppo&#8230;) Potete sempre fare figura al bar con gli amici!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>tante informazioni e classifiche sui numeri primi<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":3,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[157,214],"tags":[],"class_list":["post-8500","post","type-post","status-publish","format-standard","hentry","category-link","category-matematica_light"],"modified_by":null,"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/phh2yV-2d6","jetpack-related-posts":[{"id":36233,"url":"https:\/\/xmau.com\/notiziole\/2026\/03\/11\/numeri-primoriali-e-compositoriali\/","url_meta":{"origin":8500,"position":0},"title":"Numeri primoriali e compositoriali","author":".mau.","date":"2026-03-11","format":false,"excerpt":"Perch\u00e9 i fattoriali sono troppo mainstream","rel":"","context":"In &quot;mate-light 2026&quot;","block_context":{"text":"mate-light 2026","link":"https:\/\/xmau.com\/notiziole\/category\/matematica_light\/matelight-2026\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":16009,"url":"https:\/\/xmau.com\/notiziole\/2017\/12\/31\/quizzino-della-domenica-quanti-primi\/","url_meta":{"origin":8500,"position":1},"title":"Quizzino della domenica: quanti primi!","author":".mau.","date":"2017-12-31","format":false,"excerpt":"Sapete come Euclide dimostr\u00f2 che c'erano infiniti numeri primi? Disse \"beh, se ce ne fossero un numero finito li possiamo prendere tutti, moltiplicarli tra loro, e poi sommare 1. I casi sono due: o questo numerone \u00e8 primo, oppure \u00e8 scomponibile in fattori primi che per\u00f2 non possono essere quelli\u2026","rel":"","context":"In &quot;giochi&quot;","block_context":{"text":"giochi","link":"https:\/\/xmau.com\/notiziole\/category\/giochi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/xmau.com\/notiziole\/wp-content\/uploads\/sites\/6\/2017\/12\/q289a.png?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/xmau.com\/notiziole\/wp-content\/uploads\/sites\/6\/2017\/12\/q289a.png?resize=350%2C200 1x, https:\/\/i0.wp.com\/xmau.com\/notiziole\/wp-content\/uploads\/sites\/6\/2017\/12\/q289a.png?resize=525%2C300 1.5x"},"classes":[]},{"id":29908,"url":"https:\/\/xmau.com\/notiziole\/2024\/10\/23\/trovato-un-nuovo-primo-di-mersenne\/","url_meta":{"origin":8500,"position":2},"title":"Trovato un nuovo primo di Mersenne!","author":".mau.","date":"2024-10-23","format":false,"excerpt":"2136279841\u22121 \u00e8 un numero primo","rel":"","context":"In &quot;mate-light-2024&quot;","block_context":{"text":"mate-light-2024","link":"https:\/\/xmau.com\/notiziole\/category\/matematica_light\/matelight-2024\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":26948,"url":"https:\/\/xmau.com\/notiziole\/2023\/08\/13\/quizzino-della-domenica-primi-somma-e-differenza-di-primi\/","url_meta":{"origin":8500,"position":3},"title":"Quizzino della domenica: Primi somma e differenza di primi","author":".mau.","date":"2023-08-13","format":false,"excerpt":"Quanti e quali sono i numeri primi che sono anche somma e differenza di due numeri primi? (Ricordo che 1 non \u00e8 un numero primo) (trovate un aiutino sul mio sito, alla pagina https:\/\/xmau.com\/quizzini\/p656.html; la risposta verr\u00e0 postata l\u00ec il prossimo mercoled\u00ec. Problema da Joe Roberts, Lure of the integers,\u2026","rel":"","context":"In &quot;giochi&quot;","block_context":{"text":"giochi","link":"https:\/\/xmau.com\/notiziole\/category\/giochi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/xmau.com\/notiziole\/wp-content\/uploads\/sites\/6\/2023\/08\/q656a.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":25460,"url":"https:\/\/xmau.com\/notiziole\/2022\/12\/23\/primel\/","url_meta":{"origin":8500,"position":4},"title":"primel","author":".mau.","date":"2022-12-23","format":false,"excerpt":"Wordle, ma con i numeri primi.","rel":"","context":"In &quot;giochi&quot;","block_context":{"text":"giochi","link":"https:\/\/xmau.com\/notiziole\/category\/giochi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/xmau.com\/notiziole\/wp-content\/uploads\/sites\/6\/2022\/12\/primel-215x300.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":32740,"url":"https:\/\/xmau.com\/notiziole\/2025\/06\/22\/quizzino-della-domenica-solo-primi\/","url_meta":{"origin":8500,"position":5},"title":"Quizzino della domenica: Solo primi","author":".mau.","date":"2025-06-22","format":false,"excerpt":"753 - algebretta Siete in grado di mettere in fila i quattordici numeri da 0 a 13 in modo tale che la somma di due numeri consecutivi sia sempre un numero primo? Ricordo che 1 non \u00e8 un numero primo. (trovate un aiutino sul mio sito, alla pagina https:\/\/xmau.com\/quizzini\/p753.html; la\u2026","rel":"","context":"In &quot;giochi&quot;","block_context":{"text":"giochi","link":"https:\/\/xmau.com\/notiziole\/category\/giochi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/xmau.com\/notiziole\/wp-content\/uploads\/sites\/6\/2025\/06\/q753a.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/posts\/8500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/comments?post=8500"}],"version-history":[{"count":0,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/posts\/8500\/revisions"}],"wp:attachment":[{"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/media?parent=8500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/categories?post=8500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/tags?post=8500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}