{"id":7234,"date":"2009-07-15T00:00:00","date_gmt":"2009-07-15T00:00:00","guid":{"rendered":"http:\/\/xmau.com\/wp\/notiziole\/2009\/07\/15\/adesso_tutti_zi\/"},"modified":"2009-07-15T00:00:00","modified_gmt":"2009-07-15T00:00:00","slug":"adesso_tutti_zi","status":"publish","type":"post","link":"https:\/\/xmau.com\/notiziole\/2009\/07\/15\/adesso_tutti_zi\/","title":{"rendered":"adesso tutti zitti?"},"content":{"rendered":"<p>In un modo o nell&#8217;altro, il 14 luglio di silenzio \u00e8 passato. Io il cerotto blu lo lascio, perch\u00e9 i timori per la libert\u00e0 di stampa ce li ho ancora; ma so bene che la cosa non significa molto.<br \/>\nQuello che dovrebbe succedere \u00e8 che si <strong>faccia<\/strong> qualcosa; e almeno per quanto mi riguarda &#8220;fare&#8221; non significa mettere il cerottino oppure il bel posterino, ma metterci del proprio. Non credo che uno cento mille blog possano spostare alcunch\u00e9, per\u00f2 sono assolutamente certo che uno cento mille cartellini\/cerotti non servano assolutamente a nulla se non a crogiolarsi nell&#8217;idea di essere &#8220;importanti&#8221;. Vediamo se i fatti mi smentiranno e si inizier\u00e0 a vedere pi\u00f9 informazione da parte di quelli che si lamentano per l&#8217;attentato alla libera informazione. (Massimo rispetto per chi non ha alcun interesse al riguardo e ritiene il proprio blog un posto per postare fuffa: la sua \u00e8 una scelta coerente e legittima, ci mancherebbe altro!)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>lo &#8220;sciopero dei blog&#8221; serve solo se poi si fa qualcosa di serio.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":3,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[535],"tags":[],"class_list":["post-7234","post","type-post","status-publish","format-standard","hentry","category-pipponi"],"modified_by":null,"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/phh2yV-1SG","jetpack-related-posts":[{"id":4304,"url":"https:\/\/xmau.com\/notiziole\/2006\/07\/23\/non_sono_nei_top100\/","url_meta":{"origin":7234,"position":0},"title":"non sono nei top100","author":".mau.","date":"2006-07-23","format":false,"excerpt":"nella classifica dei blog italiani pi\u00f9 seguiti non ci sono.","rel":"","context":"In &quot;admin&quot;","block_context":{"text":"admin","link":"https:\/\/xmau.com\/notiziole\/category\/admin\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2399,"url":"https:\/\/xmau.com\/notiziole\/2003\/06\/25\/percentuali\/","url_meta":{"origin":7234,"position":1},"title":"percentuali","author":".mau.","date":"2003-06-25","format":false,"excerpt":"Ho deciso di creare una nuova categoria del blog, per dare una maggior visibilit\u00e0 agli strafalcioni matematici che si trovano ovunque. \"Innumeracy\", la chiama A.K.Dewdney. Iniziamo con la frase del ministro degli Interni Pisanu, come citata da Kataweb: Gli immigrati regolari in Italia sono il 3,8 per cento, la stessa\u2026","rel":"","context":"In &quot;povera_matematica&quot;","block_context":{"text":"povera_matematica","link":"https:\/\/xmau.com\/notiziole\/category\/povera_matematica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":7106,"url":"https:\/\/xmau.com\/notiziole\/2009\/05\/21\/se_non_e_google\/","url_meta":{"origin":7234,"position":2},"title":"se non \u00e8 Google, \u00e8 Yahoo!","author":".mau.","date":"2009-05-21","format":false,"excerpt":"l'oligarchia dei motori di ricerca \u00e8 peggiore di quanto pensassi: Altavista e AlltheWeb sono in realt\u00e0 Yahoo!","rel":"","context":"In &quot;IA e informatica&quot;","block_context":{"text":"IA e informatica","link":"https:\/\/xmau.com\/notiziole\/category\/ia\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":29915,"url":"https:\/\/xmau.com\/notiziole\/2024\/10\/24\/la-carica-dei-cento-e-uno\/","url_meta":{"origin":7234,"position":3},"title":"La carica dei cento e uno","author":".mau.","date":"2024-10-24","format":false,"excerpt":"Ci sar\u00e0 davvero quel messaggio nascosto?","rel":"","context":"In &quot;curiosita'&quot;","block_context":{"text":"curiosita'","link":"https:\/\/xmau.com\/notiziole\/category\/curiosita\/"},"img":{"alt_text":"screenshot del film","src":"https:\/\/i0.wp.com\/xmau.com\/notiziole\/wp-content\/uploads\/sites\/6\/2024\/10\/101.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":13722,"url":"https:\/\/xmau.com\/notiziole\/2016\/08\/14\/carnevale-della-matematica-100-goto-popinga\/","url_meta":{"origin":7234,"position":4},"title":"Carnevale della Matematica #100: GOTO Popinga","author":".mau.","date":"2016-08-14","format":false,"excerpt":"Cento edizioni di un'iniziativa sono davvero tante. \u00c8 giusto insomma andare a festeggiare chez Popinga il pi\u00f9 longevo dei Carnevali sui blog!","rel":"","context":"In &quot;link&quot;","block_context":{"text":"link","link":"https:\/\/xmau.com\/notiziole\/category\/link\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8773,"url":"https:\/\/xmau.com\/notiziole\/2012\/03\/01\/big_bertha\/","url_meta":{"origin":7234,"position":5},"title":"Big Bertha","author":".mau.","date":"2012-03-01","format":false,"excerpt":"Qualcuno ne sa di economia?","rel":"","context":"In &quot;varie&quot;","block_context":{"text":"varie","link":"https:\/\/xmau.com\/notiziole\/category\/varie\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/posts\/7234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/comments?post=7234"}],"version-history":[{"count":0,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/posts\/7234\/revisions"}],"wp:attachment":[{"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/media?parent=7234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/categories?post=7234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/tags?post=7234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}