{"id":3502,"date":"2005-05-22T19:30:27","date_gmt":"2005-05-22T19:30:27","guid":{"rendered":"http:\/\/xmau.com\/wp\/notiziole\/2005\/05\/22\/rotazione_degli_armadi\/"},"modified":"2005-05-22T19:30:27","modified_gmt":"2005-05-22T19:30:27","slug":"rotazione_degli_armadi","status":"publish","type":"post","link":"https:\/\/xmau.com\/notiziole\/2005\/05\/22\/rotazione_degli_armadi\/","title":{"rendered":"Rotazione degli armadi"},"content":{"rendered":"<p>Sono reduce dalla solita operazione che si fa due volte l&#8217;anno: prendere dagli armadi la roba della stagione passata e dal nascondiglio deputato la roba per la stagione entrante, e fare ammuina. Il risultato finale dovrebbe essere simile a quello iniziale: peccato che dopo varie ore di lavoro, e un paio di borse di roba che si \u00e8 deciso di buttare via, ci siamo al solito trovati pi\u00f9 cose di quelle di partenza. E non sto nemmeno a parlare del momento di mezzo, dove la roba non poteva stare n\u00e9 negli armadi n\u00e9 nel nascondiglio, e quindi \u00e8 stata sparsa per la casa. Aggiungo solo che le gatte si sono lamentate della situazione.<br \/>\nMa non \u00e8 finita: ci sono ancora le scarpe&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ma quanti vestiti ci sono?<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":3,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[12],"tags":[],"class_list":["post-3502","post","type-post","status-publish","format-standard","hentry","category-y2005_io"],"modified_by":null,"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/phh2yV-Uu","jetpack-related-posts":[{"id":4440,"url":"https:\/\/xmau.com\/notiziole\/2006\/10\/07\/autunno_2\/","url_meta":{"origin":3502,"position":0},"title":"autunno 2","author":".mau.","date":"2006-10-07","format":false,"excerpt":"si mette la roba invernale!","rel":"","context":"In &quot;y2006_io&quot;","block_context":{"text":"y2006_io","link":"https:\/\/xmau.com\/notiziole\/category\/y2006_io\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8583,"url":"https:\/\/xmau.com\/notiziole\/2011\/10\/11\/armadi\/","url_meta":{"origin":3502,"position":1},"title":"armadi","author":".mau.","date":"2011-10-11","format":false,"excerpt":"Per chi si preoccupava della mancanza del mio post biannuale: tra domenica e ieri c'\u00e8 stato il giro degli armadi, a cui per fortuna ho dovuto contribuire poco. E infatti ritorna il caldo.","rel":"","context":"In &quot;io&quot;","block_context":{"text":"io","link":"https:\/\/xmau.com\/notiziole\/category\/io\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":20940,"url":"https:\/\/xmau.com\/notiziole\/2020\/08\/27\/traslochi-2\/","url_meta":{"origin":3502,"position":2},"title":"traslochi","author":".mau.","date":"2020-08-27","format":false,"excerpt":"Con la storia dello smart working lungo, la mia azienda ha deciso di togliere il \"posto fisso\", il che significa sgombrare tutti i nostri effetti personali, anche perch\u00e9 dovrebbero esserci dei lavori di ristrutturazione. Non mi \u00e8 ben chiaro cosa possono fare nella mia sede, che per come \u00e8 fatta\u2026","rel":"","context":"In &quot;io&quot;","block_context":{"text":"io","link":"https:\/\/xmau.com\/notiziole\/category\/io\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2926,"url":"https:\/\/xmau.com\/notiziole\/2004\/05\/16\/estate\/","url_meta":{"origin":3502,"position":3},"title":"estate","author":".mau.","date":"2004-05-16","format":false,"excerpt":"abbiamo deciso che ci siamo scocciati, ed \u00e8 ufficialmente arrivata la bella stagione. In pratica? pranzo in terrazzo, alla facciaccia dei vicini :-) e giro degli armadi :-(","rel":"","context":"In &quot;y2004_io&quot;","block_context":{"text":"y2004_io","link":"https:\/\/xmau.com\/notiziole\/category\/y2004_io\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5585,"url":"https:\/\/xmau.com\/notiziole\/2007\/12\/20\/oggi_non_e_gior\/","url_meta":{"origin":3502,"position":4},"title":"oggi non \u00e8 giornata","author":".mau.","date":"2007-12-20","format":false,"excerpt":"oggi dimentico di tutto di pi\u00f9","rel":"","context":"In &quot;io-2007&quot;","block_context":{"text":"io-2007","link":"https:\/\/xmau.com\/notiziole\/category\/io\/io-2007\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2349,"url":"https:\/\/xmau.com\/notiziole\/2003\/06\/02\/cantina\/","url_meta":{"origin":3502,"position":5},"title":"Cantina","author":".mau.","date":"2003-06-02","format":false,"excerpt":"La domenica mattina \u00e8 stata passata a mettere a posto la cantina, che era stata usata come ripostiglio. Avevamo a disposizione un armadio e delle scaffalature Ikea che avevamo smontato dalla casa di via Taramelli. Miracolo: siamo riusciti a rimontarli per la seconda volta, primato almeno provinciale secondo le classifiche\u2026","rel":"","context":"In &quot;y2005_io&quot;","block_context":{"text":"y2005_io","link":"https:\/\/xmau.com\/notiziole\/category\/y2005_io\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/posts\/3502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/comments?post=3502"}],"version-history":[{"count":0,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/posts\/3502\/revisions"}],"wp:attachment":[{"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/media?parent=3502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/categories?post=3502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/tags?post=3502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}