{"id":1971,"date":"2002-04-05T15:44:23","date_gmt":"2002-04-05T15:44:23","guid":{"rendered":"http:\/\/xmau.com\/wp\/notiziole\/2002\/04\/05\/sono_tornato\/"},"modified":"2002-04-05T15:44:23","modified_gmt":"2002-04-05T15:44:23","slug":"sono_tornato","status":"publish","type":"post","link":"https:\/\/xmau.com\/notiziole\/2002\/04\/05\/sono_tornato\/","title":{"rendered":"Sono tornato&#8230;"},"content":{"rendered":"<p>dopo una settimana in vacanza in Belgio, ritorno a divertirmi (si fa per dire) in ufficio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>dopo una settimana in vacanza in Belgio, ritorno a divertirmi (si fa per dire) in ufficio.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":3,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[895],"tags":[],"class_list":["post-1971","post","type-post","status-publish","format-standard","hentry","category-varie-2001-02"],"modified_by":null,"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/phh2yV-vN","jetpack-related-posts":[{"id":10426,"url":"https:\/\/xmau.com\/notiziole\/2014\/08\/16\/riposo-si-fa-per-dire\/","url_meta":{"origin":1971,"position":0},"title":"riposo (si fa per dire)","author":".mau.","date":"2014-08-16","format":false,"excerpt":"vacanza? no, soggiorno marino","rel":"","context":"In &quot;io&quot;","block_context":{"text":"io","link":"https:\/\/xmau.com\/notiziole\/category\/io\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2045,"url":"https:\/\/xmau.com\/notiziole\/2002\/09\/02\/sono_davvero_tornati_tutti\/","url_meta":{"origin":1971,"position":1},"title":"sono DAVVERO tornati tutti","author":".mau.","date":"2002-09-02","format":false,"excerpt":"Il mio indicatore di traffico \u00e8 il cavalcautostrada di MilanoFiori. La settimana dopo ferragosto non c'era coda: due o tre macchine in attesa di immettersi nella rotonda alla fine del ponte. La settimana scorsa, la coda arrivava all'inizio del ponte stesso. Oggi iniziava prima della rotonda prima di quella del\u2026","rel":"","context":"In &quot;2001-02&quot;","block_context":{"text":"2001-02","link":"https:\/\/xmau.com\/notiziole\/category\/varie\/varie-2001-02\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2082,"url":"https:\/\/xmau.com\/notiziole\/2002\/10\/16\/i_mondiali_di_ciclismo\/","url_meta":{"origin":1971,"position":2},"title":"i mondiali di ciclismo","author":".mau.","date":"2002-10-16","format":false,"excerpt":"Ho colpevolmente tralasciato di commentare l'avvenimento sportivo della settimana, vale a dire i mondiali di ciclismo (oh, ognuno ha le sue preferenze!) Dopo dieci anni, la maglia arcobaleno \u00e8 tornata sulle spalle di un italiano, l'ineffabile Mario Cipollini. Il nostro non \u00e8 mai stato in cima alle mie preferenze: sono\u2026","rel":"","context":"In &quot;2001-02&quot;","block_context":{"text":"2001-02","link":"https:\/\/xmau.com\/notiziole\/category\/varie\/varie-2001-02\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":23043,"url":"https:\/\/xmau.com\/notiziole\/2021\/10\/07\/sono-tornato-in-ufficio\/","url_meta":{"origin":1971,"position":3},"title":"Sono tornato in ufficio","author":".mau.","date":"2021-10-07","format":false,"excerpt":"Anche se per un solo giorno la settimana, e in una sede che non \u00e8 la mia","rel":"","context":"In &quot;io&quot;","block_context":{"text":"io","link":"https:\/\/xmau.com\/notiziole\/category\/io\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1992,"url":"https:\/\/xmau.com\/notiziole\/2002\/06\/17\/promesse_elettorali_mantenute\/","url_meta":{"origin":1971,"position":4},"title":"Promesse elettorali mantenute","author":".mau.","date":"2002-06-17","format":false,"excerpt":"Ricordate la mia lamentela sulla pista ciclabile di Buccinasco, che si erano dimenticati di asfaltare di nuovo dopo avere tolto la vecchia pavimentazione - o almeno quello che ne era rimasto? Bene, oggi dopo una delle mie solite settimane in giro per l'Italia per motivi di lavoro sono tornato a\u2026","rel":"","context":"In &quot;2001-02&quot;","block_context":{"text":"2001-02","link":"https:\/\/xmau.com\/notiziole\/category\/varie\/varie-2001-02\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1903,"url":"https:\/\/xmau.com\/notiziole\/2001\/10\/15\/previsioni_del_tempo\/","url_meta":{"origin":1971,"position":5},"title":"Previsioni del tempo","author":".mau.","date":"2001-10-15","format":false,"excerpt":"Un anno fa, qui in Piemonte stavamo per essere sommersi dall'alluvione: domenica 15 ricordo che la sede del mio ufficio non era gi\u00e0 raggiungibile. Oggi sono uscito in bicicletta, e sono rimasto in t-shirt perch\u00e9 faceva troppo caldo. La differenza non \u00e8 poi cos\u00ec grande come pu\u00f2 sembrare: in effetti,\u2026","rel":"","context":"In &quot;2001-02&quot;","block_context":{"text":"2001-02","link":"https:\/\/xmau.com\/notiziole\/category\/varie\/varie-2001-02\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/posts\/1971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/comments?post=1971"}],"version-history":[{"count":0,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/posts\/1971\/revisions"}],"wp:attachment":[{"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/media?parent=1971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/categories?post=1971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/tags?post=1971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}