{"id":19513,"date":"2019-11-07T04:04:04","date_gmt":"2019-11-07T03:04:04","guid":{"rendered":"https:\/\/xmau.com\/wp\/notiziole\/?p=19513"},"modified":"2019-11-06T11:01:31","modified_gmt":"2019-11-06T10:01:31","slug":"ilva","status":"publish","type":"post","link":"https:\/\/xmau.com\/notiziole\/2019\/11\/07\/ilva\/","title":{"rendered":"ILVA"},"content":{"rendered":"<p>No, non aggiungo il mio pensiero su cosa fare dell&#8217;ILVA. Non ho assolutamente le competenze non dico per dare una soluzione, ma neppure per parlare con cognizione di causa. Tutto quello che posso fare \u00e8 notare alcune cose.<br \/>\n&#8211; Ho letto che l&#8217;ILVA vale l&#8217;1,5% del PIL italiano, quindi circa 29 miliardi l&#8217;anno. Il suo fatturato 2016 <a href=\"https:\/\/www.industriaitaliana.it\/i-veri-numeri-dellilva-e-la-politica-che-dovrebbe-finalmente-starne-fuori\/\">era di 2,2 miliardi<\/a>: anche considerando l&#8217;indotto e un ipotetico raddoppio della capacit\u00e0 produttiva siamo ben lontani.<br \/>\n&#8211; Scudo penale: siamo abituati a leggi che cambiano artatamente i limiti, chi ha la mia et\u00e0 <a href=\"https:\/\/ricerca.repubblica.it\/repubblica\/archivio\/repubblica\/1987\/08\/26\/atrazina-acqua-torna-potabile-per-decreto.html\">si ricorda certo dell&#8217;atrazina<\/a> e anche chi \u00e8 pi\u00f9 giovane dovrebbe ricordarsi <a href=\"https:\/\/www.ilpost.it\/2011\/04\/16\/la-storia-del-rogo-della-thyssenkrupp\/\">della ThyssenKrupp<\/a>. La fregatura \u00e8 che mentre in quest&#8217;ultimo caso la (mancata) sicurezza era nei confronti degli operai, l&#8217;inquinamento dell&#8217;ILVA \u00e8 per tutta la zona intorno: insomma, rimane la scelta su quanto morire. Ci\u00f2 detto, non sono riuscito a capire quanto tempo ci voglia per rientrare in parametri accettabili di inquinamento nel caso si facessero davvero questi lavori: la mia preoccupazione \u00e8 che quello dello scudo sia un modo per non fare nulla e risparmiare soldi.<br \/>\n&#8211; Occupazione: \u00e8 il solito ricatto &#8220;preferite morire di fame o di cancro?&#8221; che abbiamo visto tante volte. Premesso che non credo in una riconversione post-industriale della zona &#8211; soprattutto in tempi brevi &#8211; non ho proprio idea di quale sia la scelta meno peggiore nel breve termine. Il vero guaio \u00e8 che mi pare che non lo sappia nessuno.<\/p>\n<p>Scusate se per una volta non ho fatto lo scodellatore di soluzioni :-)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Parlare \u00e8 facile, farlo con cognizione un po&#8217; meno.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":3,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[535,936],"tags":[],"class_list":["post-19513","post","type-post","status-publish","format-standard","hentry","category-pipponi","category-pipponi-2019"],"modified_by":"xlthlx","jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/shh2yV-ilva","jetpack-related-posts":[{"id":24878,"url":"https:\/\/xmau.com\/notiziole\/2022\/09\/20\/4-miliardi-di-persone\/","url_meta":{"origin":19513,"position":0},"title":"4 miliardi di persone?","author":".mau.","date":"2022-09-20","format":false,"excerpt":"A Canale 5 hanno detto pi\u00f9 volte (ieri e oggi) che quattro miliardi di persone hanno seguito i funerali di Elisabetta II. In effetti anche Ansa conferma. Mah, anche immaginando che tantissimi indiani si siano fatti una levataccia, mi pare esagerato che una persona su due fosse davanti alla TV.\u2026","rel":"","context":"In &quot;pipponi&quot;","block_context":{"text":"pipponi","link":"https:\/\/xmau.com\/notiziole\/category\/pipponi\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4844,"url":"https:\/\/xmau.com\/notiziole\/2007\/03\/22\/ma_che_cosa_sono_poi_70_miliardi\/","url_meta":{"origin":19513,"position":1},"title":"ma che cosa sono poi 70 miliardi?","author":".mau.","date":"2007-03-22","format":false,"excerpt":"Silvio ha pagato Umberto? e che ce ne importa?","rel":"","context":"In &quot;pipponi-2007&quot;","block_context":{"text":"pipponi-2007","link":"https:\/\/xmau.com\/notiziole\/category\/pipponi\/pipponi-2007\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":21998,"url":"https:\/\/xmau.com\/notiziole\/2021\/04\/06\/no-non-proprio-119-miliardi\/","url_meta":{"origin":19513,"position":2},"title":"No, non proprio 11,9 miliardi","author":".mau.","date":"2021-04-06","format":false,"excerpt":"Il Corsera tiene a farci sapere che a causa della pandemia il bilancio INPS sar\u00e0 \"pi\u00f9 leggero di 11,9 miliardi\". Tutto molto interessante: ma come scrivevo alla mia amica Silvia, leggendo l'articolo si scopre che quei risparmi si avranno in dieci anni, e in realt\u00e0 ci si \u00e8 semplicemente messi\u2026","rel":"","context":"In &quot;pipponi&quot;","block_context":{"text":"pipponi","link":"https:\/\/xmau.com\/notiziole\/category\/pipponi\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5929,"url":"https:\/\/xmau.com\/notiziole\/2008\/04\/12\/quanto_ci_costa\/","url_meta":{"origin":19513,"position":3},"title":"Quanto ci costa il debito pubblico","author":".mau.","date":"2008-04-12","format":false,"excerpt":"due conti spannometrici","rel":"","context":"In &quot;pipponi&quot;","block_context":{"text":"pipponi","link":"https:\/\/xmau.com\/notiziole\/category\/pipponi\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":6920,"url":"https:\/\/xmau.com\/notiziole\/2009\/03\/18\/tremonti_ha_rag\/","url_meta":{"origin":19513,"position":4},"title":"Tremonti ha ragione","author":".mau.","date":"2009-03-18","format":false,"excerpt":"Unicredit ha solo fatto quattro miliardi di utile, l'anno scorso.","rel":"","context":"In &quot;pipponi&quot;","block_context":{"text":"pipponi","link":"https:\/\/xmau.com\/notiziole\/category\/pipponi\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":16641,"url":"https:\/\/xmau.com\/notiziole\/2018\/04\/12\/bidone-dellimmondizia\/","url_meta":{"origin":19513,"position":5},"title":"Bidone dell&#8217;immondizia","author":".mau.","date":"2018-04-12","format":false,"excerpt":"Non \u00e8 stato bello","rel":"","context":"In &quot;pipponi&quot;","block_context":{"text":"pipponi","link":"https:\/\/xmau.com\/notiziole\/category\/pipponi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/xmau.com\/notiziole\/wp-content\/uploads\/sites\/6\/2018\/04\/greendot.png?resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/posts\/19513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/comments?post=19513"}],"version-history":[{"count":1,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/posts\/19513\/revisions"}],"predecessor-version":[{"id":19514,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/posts\/19513\/revisions\/19514"}],"wp:attachment":[{"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/media?parent=19513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/categories?post=19513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xmau.com\/notiziole\/wp-json\/wp\/v2\/tags?post=19513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}